{"id":5141,"date":"2023-10-18T11:17:43","date_gmt":"2023-10-18T03:17:43","guid":{"rendered":"https:\/\/hghypackaging.com\/?post_type=product&#038;p=5141"},"modified":"2025-03-13T16:17:01","modified_gmt":"2025-03-13T08:17:01","slug":"maquina-de-cubiertos-biodegradables","status":"publish","type":"product","link":"https:\/\/www.hghypackaging.com\/es\/product\/maquina-de-cubiertos-biodegradables\/","title":{"rendered":"HGHY M\u00e1quina De Cubiertos Biodegradables"},"content":{"rendered":"\t\t<div data-elementor-type=\"product-post\" data-elementor-id=\"5141\" class=\"elementor elementor-5141\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6eac4c8d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6eac4c8d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50656394\" data-id=\"50656394\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-297b888 e-con-boxed e-flex e-con\" data-id=\"297b888\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2fc020b elementor-widget elementor-widget-heading\" data-id=\"2fc020b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.13.3 - 22-05-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">HGHY M\u00e1quina De Cubiertos Biodegradables\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-59d454d e-con-boxed e-flex e-con\" data-id=\"59d454d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d86880a e-con-full e-flex e-con\" data-id=\"d86880a\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cfb48a9 elementor-widget elementor-widget-video\" data-id=\"cfb48a9\" data-element_type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.13.3 - 22-05-2023 *\/\n.elementor-widget-video .elementor-widget-container{overflow:hidden;transform:translateZ(0)}.elementor-widget-video .elementor-wrapper{aspect-ratio:var(--video-aspect-ratio)}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{height:100%;width:100%;display:flex;border:none;background-color:#000}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-wrapper{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .elementor-open-inline .elementor-custom-embed-image-overlay{position:absolute;top:0;left:0;width:100%;height:100%;background-size:cover;background-position:50%}.elementor-widget-video .elementor-custom-embed-image-overlay{cursor:pointer;text-align:center}.elementor-widget-video .elementor-custom-embed-image-overlay:hover .elementor-custom-embed-play i{opacity:1}.elementor-widget-video .elementor-custom-embed-image-overlay img{display:block;width:100%}.elementor-widget-video .e-hosted-video .elementor-video{-o-object-fit:cover;object-fit:cover}.e-con-inner>.elementor-widget-video,.e-con>.elementor-widget-video{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/www.pulpmoldingchina.cn\/wp-content\/uploads\/2023\/03\/Semi-automatic-Tableware-Machine.mp4\" controls=\"\" preload=\"metadata\" controlsList=\"nodownload\" poster=\"https:\/\/www.pulpmoldingchina.cn\/wp-content\/uploads\/2023\/03\/video-picture-08.webp\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fdac51b e-con-full e-flex e-con\" data-id=\"fdac51b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d1f0cc2 elementor-widget elementor-widget-heading\" data-id=\"d1f0cc2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Sencillo, avanzado y de alta productividad<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0384af7 elementor-widget elementor-widget-text-editor\" data-id=\"0384af7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.13.3 - 22-05-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Nueva tecnolog\u00eda creada para un nuevo mercado, ha vendido m\u00e1s de 100 unidades desde su lanzamiento.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-470a228 elementor-widget elementor-widget-text-editor\" data-id=\"470a228\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"li\"><p>&#8211; Tama\u00f1o de la placa: 980 x 940 mm<\/p><p>&#8211; 1 Conformado 2 Prensado en caliente<\/p><p>&#8211; Recorte autom\u00e1tico de robots de marca internacional<\/p><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5fa2b9e e-con-boxed e-flex e-con\" data-id=\"5fa2b9e\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0319c43 elementor-widget elementor-widget-bdt-advanced-heading\" data-id=\"0319c43\" data-element_type=\"widget\" data-widget_type=\"bdt-advanced-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id =\"0319c43\" class=\"bdt-ep-advanced-heading\" data-settings=\"{&quot;titleMultiColor&quot;:&quot;no&quot;}\"><div class=\"bdt-ep-advanced-heading-content bdt-visible@m\"><div class=\"bdt-transform-origin-top-left\">_________<\/div><\/div><h4 class=\"bdt-ep-advanced-heading-title\"><span class=\"bdt-ep-advanced-heading-main-title\"><span class=\"bdt-ep-advanced-heading-main-title-inner\">Principales Caracter\u00edsticas<\/span><\/span><\/h4><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e5da38 elementor-widget elementor-widget-text-editor\" data-id=\"9e5da38\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>Sistema de control inteligente altamente rentable;<\/li><li>Producci\u00f3n flexible, precisa y estable;<\/li><li>Operaci\u00f3n y mantenimiento seguros y sencillos;<\/li><li>El pionero de Guangzhou en ciencia y tecnolog\u00eda Tecnolog\u00eda;<\/li><li>Monitoreo remoto de producci\u00f3n inteligente;<\/li><li>Dise\u00f1o integrado para recortar y apilar;<\/li><li>Conectividad de procesos inteligente a trav\u00e9s de robots.<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3edd3ad e-con-boxed e-flex e-con\" data-id=\"3edd3ad\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ee00a68 elementor-widget elementor-widget-bdt-advanced-heading\" data-id=\"ee00a68\" data-element_type=\"widget\" data-widget_type=\"bdt-advanced-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id =\"ee00a68\" class=\"bdt-ep-advanced-heading\" data-settings=\"{&quot;titleMultiColor&quot;:&quot;no&quot;}\"><div class=\"bdt-ep-advanced-heading-content bdt-visible@m\"><div class=\"bdt-transform-origin-top-left\">_____________<\/div><\/div><h4 class=\"bdt-ep-advanced-heading-title\"><span class=\"bdt-ep-advanced-heading-main-title\"><span class=\"bdt-ep-advanced-heading-main-title-inner\">Par\u00e1metros T\u00e9cnicos<\/span><\/span><\/h4><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5afee0 elementor-widget elementor-widget-text-editor\" data-id=\"d5afee0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<table><thead><tr><th>Modelo<\/th><th colspan=\"3\">BW2-9895C<\/th><\/tr><\/thead><tbody><tr><td>Aplicaci\u00f3n del Producto<\/td><td colspan=\"3\">Vajilla Desechable, Vasos de Papel, Cart\u00f3n de Huevo Premium<\/td><\/tr><tr><td>Capacidad Diaria<\/td><td colspan=\"3\">500 KG ( Basado en los Productos )<\/td><\/tr><tr><td>Tama\u00f1o de Placa<\/td><td colspan=\"3\">980 \u00d7 940 mm<\/td><\/tr><tr><td>Energ\u00eda de Calefacci\u00f3n<\/td><td colspan=\"3\">Electricidad \/ Aceite T\u00e9rmico<\/td><\/tr><tr><td>M\u00e9todo de Moldeo<\/td><td colspan=\"3\">Reciprocante<\/td><\/tr><tr><td>M\u00e9todo de Prensado en Caliente \/ Presi\u00f3n<\/td><td colspan=\"3\">Sistema Hidr\u00e1ulico \/ Presi\u00f3n M\u00e1xima de 30 Toneladas<\/td><\/tr><tr><td>Protecci\u00f3n de Seguridad<\/td><td colspan=\"3\">Dise\u00f1o de Autocierre y Parada Autom\u00e1tica<\/td><\/tr><tr><td>Altura \/ Espesor M\u00e1ximo del Producto<\/td><td colspan=\"3\">60 mm \/ 0.8 mm<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-652ad4d e-con-boxed e-flex e-con\" data-id=\"652ad4d\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e15fbb8 elementor-widget elementor-widget-bdt-advanced-heading\" data-id=\"e15fbb8\" data-element_type=\"widget\" data-widget_type=\"bdt-advanced-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id =\"e15fbb8\" class=\"bdt-ep-advanced-heading\" data-settings=\"{&quot;titleMultiColor&quot;:&quot;no&quot;}\"><div class=\"bdt-ep-advanced-heading-content bdt-visible@m\"><div class=\"bdt-transform-origin-top-left\">____________<\/div><\/div><h4 class=\"bdt-ep-advanced-heading-title\"><span class=\"bdt-ep-advanced-heading-main-title\"><span class=\"bdt-ep-advanced-heading-main-title-inner\">Proceso de producci\u00f3n<\/span><\/span><\/h4><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a1d512 elementor-widget elementor-widget-text-editor\" data-id=\"5a1d512\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>HGHY M\u00e1quina\u00a0De Cubiertos Biodegradables se compone de un sistema de pulpa, m\u00faltiples conjuntos de sistemas principales (que incluyen conformado, prensado en caliente, recorte, apilado y robot), sistema auxiliar, fabricaci\u00f3n de cubiertos biodegradables y cubiertos ecologicos.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5504c8a e-transform elementor-widget elementor-widget-image\" data-id=\"5504c8a\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.02,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.13.3 - 22-05-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"357\" src=\"https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Production-Process-2-scaled.webp\" class=\"attachment-full size-full wp-image-4290\" alt=\"sugarcane bagasse tableware making machine\" srcset=\"https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Production-Process-2-scaled.webp 2560w, https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Production-Process-2-scaled-600x84.webp 600w, https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Production-Process-2-300x42.webp 300w, https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Production-Process-2-1024x143.webp 1024w, https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Production-Process-2-768x107.webp 768w, https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Production-Process-2-1536x214.webp 1536w, https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Production-Process-2-2048x286.webp 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f0b217 e-con-boxed e-flex e-con\" data-id=\"7f0b217\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f6dbfc4 elementor-widget elementor-widget-bdt-advanced-heading\" data-id=\"f6dbfc4\" data-element_type=\"widget\" data-widget_type=\"bdt-advanced-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id =\"f6dbfc4\" class=\"bdt-ep-advanced-heading\" data-settings=\"{&quot;titleMultiColor&quot;:&quot;no&quot;}\"><div class=\"bdt-ep-advanced-heading-content bdt-visible@m\"><div class=\"bdt-transform-origin-top-left\">_________<\/div><\/div><h4 class=\"bdt-ep-advanced-heading-title\"><span class=\"bdt-ep-advanced-heading-main-title\"><span class=\"bdt-ep-advanced-heading-main-title-inner\">Casos De Proyectos<\/span><\/span><\/h4><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fc4bd6 e-transform elementor-widget elementor-widget-image\" data-id=\"2fc4bd6\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.03,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1500\" height=\"624\" src=\"https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Factory-case-1.webp\" class=\"attachment-full size-full wp-image-4285\" alt=\"sugarcane bagasse tableware making machine\" srcset=\"https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Factory-case-1.webp 1500w, https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Factory-case-1-600x250.webp 600w, https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Factory-case-1-300x125.webp 300w, https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Factory-case-1-1024x426.webp 1024w, https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Factory-case-1-768x319.webp 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3fc7b77 e-con-boxed e-flex e-con\" data-id=\"3fc7b77\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2dbbc7d elementor-widget elementor-widget-bdt-advanced-heading\" data-id=\"2dbbc7d\" data-element_type=\"widget\" data-widget_type=\"bdt-advanced-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id =\"2dbbc7d\" class=\"bdt-ep-advanced-heading\" data-settings=\"{&quot;titleMultiColor&quot;:&quot;no&quot;}\"><div class=\"bdt-ep-advanced-heading-content bdt-visible@m\"><div class=\"bdt-transform-origin-top-left\">________<\/div><\/div><h4 class=\"bdt-ep-advanced-heading-title\"><span class=\"bdt-ep-advanced-heading-main-title\"><span class=\"bdt-ep-advanced-heading-main-title-inner\">Aplicaciones<\/span><\/span><\/h4><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dca3819 e-con-boxed e-flex e-con\" data-id=\"dca3819\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-54fe669 e-transform elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"54fe669\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.03,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"482\" src=\"https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Multiple-Applications-01-1.webp\" class=\"attachment-full size-full wp-image-4287\" alt=\"sugarcane bagasse tableware making machine\" srcset=\"https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Multiple-Applications-01-1.webp 800w, https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Multiple-Applications-01-1-600x362.webp 600w, https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Multiple-Applications-01-1-300x181.webp 300w, https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Multiple-Applications-01-1-768x463.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66caeb7 e-transform elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"66caeb7\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.03,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Multiple-Applications-02-1.webp\" class=\"attachment-full size-full wp-image-4288\" alt=\"paper tray making machine\" srcset=\"https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Multiple-Applications-02-1.webp 800w, https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Multiple-Applications-02-1-600x398.webp 600w, https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Multiple-Applications-02-1-300x199.webp 300w, https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/03\/Multiple-Applications-02-1-768x509.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca2d212 e-con-boxed e-flex e-con\" data-id=\"ca2d212\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c2ec488 elementor-widget elementor-widget-bdt-advanced-heading\" data-id=\"c2ec488\" data-element_type=\"widget\" data-widget_type=\"bdt-advanced-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id =\"c2ec488\" class=\"bdt-ep-advanced-heading\" data-settings=\"{&quot;titleMultiColor&quot;:&quot;no&quot;}\"><div class=\"bdt-ep-advanced-heading-content bdt-visible@m\"><div class=\"bdt-transform-origin-top-left\">________<\/div><\/div><h4 class=\"bdt-ep-advanced-heading-title\"><span class=\"bdt-ep-advanced-heading-main-title\"><span class=\"bdt-ep-advanced-heading-main-title-inner\">Materia Prima<\/span><\/span><\/h4><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ec3d5a elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"1ec3d5a\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.13.3 - 22-05-2023 *\/\n.elementor-widget-image-box .elementor-image-box-content{width:100%}@media (min-width:768px){.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper,.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{display:flex}.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{text-align:right;flex-direction:row-reverse}.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper{text-align:left;flex-direction:row}.elementor-widget-image-box.elementor-position-top .elementor-image-box-img{margin:auto}.elementor-widget-image-box.elementor-vertical-align-top .elementor-image-box-wrapper{align-items:flex-start}.elementor-widget-image-box.elementor-vertical-align-middle .elementor-image-box-wrapper{align-items:center}.elementor-widget-image-box.elementor-vertical-align-bottom .elementor-image-box-wrapper{align-items:flex-end}}@media (max-width:767px){.elementor-widget-image-box .elementor-image-box-img{margin-left:auto!important;margin-right:auto!important;margin-bottom:15px}}.elementor-widget-image-box .elementor-image-box-img{display:inline-block}.elementor-widget-image-box .elementor-image-box-title a{color:inherit}.elementor-widget-image-box .elementor-image-box-wrapper{text-align:center}.elementor-widget-image-box .elementor-image-box-description{margin:0}<\/style><div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"650\" height=\"490\" src=\"https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/09\/bagass.webp\" class=\"elementor-animation-grow attachment-full size-full wp-image-4427\" alt=\"Pulp Molding Tableware Machine\" srcset=\"https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/09\/bagass.webp 650w, https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/09\/bagass-600x452.webp 600w, https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/09\/bagass-300x226.webp 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\">Bagazo De Ca\u00f1a De Az\u00facar<\/h4><p class=\"elementor-image-box-description\">El M\u00e1quina De Cubiertos Biodegradables juega un papel crucial en la transformaci\u00f3n del bagazo, un subproducto de los ingenios azucareros y una materia prima com\u00fan para la fibra de papel. Las fibras de bagazo tienen una longitud promedio que oscila entre 1,47 y 3,04 mm, con medidas espec\u00edficas entre 1,0 y 2,34 mm. Este material exhibe resistencia y dureza moderadas, lo que lo hace muy adecuado para crear productos de moldeo de pulpa. Actualmente, el bagazo de ca\u00f1a de az\u00facar se utiliza ampliamente en la producci\u00f3n de loncheras y vajillas. Adem\u00e1s, se emplea en la elaboraci\u00f3n de soportes para tel\u00e9fonos m\u00f3viles y envases de cosm\u00e9ticos de alta calidad.<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69935af elementor-position-right elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"69935af\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"880\" height=\"495\" src=\"https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/09\/bamboo.webp\" class=\"elementor-animation-grow attachment-full size-full wp-image-4426\" alt=\"Pulp Molding Tableware Machine\" srcset=\"https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/09\/bamboo.webp 880w, https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/09\/bamboo-600x338.webp 600w, https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/09\/bamboo-300x169.webp 300w, https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/09\/bamboo-768x432.webp 768w\" sizes=\"(max-width: 880px) 100vw, 880px\" \/><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\">Bamb\u00fa<\/h4><p class=\"elementor-image-box-description\">HGHY M\u00e1quina De Cubiertos Biodegradables utiliza pulpa de bamb\u00fa, un material ecol\u00f3gico con propiedades antibacterianas naturales. Derivado de variedades de bamb\u00fa de r\u00e1pida regeneraci\u00f3n, es inodoro e hipoalerg\u00e9nico. Procesada con m\u00e9todos de sulfato y sosa c\u00e1ustica, la pulpa resultante es fina, suave y exhibe propiedades de gran volumen y desgarro, junto con una notable resistencia mec\u00e1nica.<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05571ae elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"05571ae\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"538\" height=\"404\" src=\"https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/09\/three.webp\" class=\"elementor-animation-grow attachment-full size-full wp-image-4428\" alt=\"Pulp Molding Tableware Machine\" srcset=\"https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/09\/three.webp 538w, https:\/\/www.hghypackaging.com\/wp-content\/uploads\/2023\/09\/three-300x225.webp 300w\" sizes=\"(max-width: 538px) 100vw, 538px\" \/><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\">Pulpa de madera<\/h4><p class=\"elementor-image-box-description\">HGHY M\u00e1quina De Cubiertos Biodegradables es un equipo de \u00faltima generaci\u00f3n dise\u00f1ado para convertir eficientemente el bagazo, subproducto de los ingenios azucareros, en productos moldeados de pulpa de alta calidad. La pulpa de madera, por otro lado, se deriva de la madera y se puede clasificar en t\u00e9rminos generales en dos tipos, madera de con\u00edferas y madera dura, seg\u00fan factores como la fuente de la madera, las t\u00e9cnicas de elaboraci\u00f3n de pulpa y los usos previstos de la pulpa.<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cbe970d e-con-boxed e-flex e-con\" data-id=\"cbe970d\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-462be9f elementor-widget elementor-widget-bdt-advanced-heading\" data-id=\"462be9f\" data-element_type=\"widget\" data-widget_type=\"bdt-advanced-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id =\"462be9f\" class=\"bdt-ep-advanced-heading\" data-settings=\"{&quot;titleMultiColor&quot;:&quot;no&quot;}\"><div class=\"bdt-ep-advanced-heading-content bdt-visible@m\"><div class=\"bdt-transform-origin-top-left\">_________________<\/div><\/div><h4 class=\"bdt-ep-advanced-heading-title\"><span class=\"bdt-ep-advanced-heading-main-title\"><span class=\"bdt-ep-advanced-heading-main-title-inner\">Preguntas frecuentes<\/span><\/span><\/h4><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4643279 elementor-widget elementor-widget-bdt-accordion\" data-id=\"4643279\" data-element_type=\"widget\" data-widget_type=\"bdt-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"bdt-ep-accordion-container\">\n            <div id=\"bdt-ep-accordion-4643279\" class=\"bdt-ep-accordion bdt-accordion\" data-bdt-accordion=\"{&quot;collapsible&quot;:true,&quot;multiple&quot;:false,&quot;transition&quot;:&quot;ease-in-out&quot;}\" data-settings=\"{&quot;id&quot;:&quot;bdt-ep-accordion-4643279&quot;,&quot;activeHash&quot;:&quot;&quot;,&quot;activeScrollspy&quot;:null,&quot;hashTopOffset&quot;:false,&quot;hashScrollspyTime&quot;:false}\">\n                                    <div class=\"bdt-ep-accordion-item\">\n                        <div class=\"bdt-ep-accordion-title bdt-accordion-title bdt-flex bdt-flex-middle bdt-flex-between\" id=\"bdt-ep-accordion-cunto-tiempo-pasar-desde-el-pedido-hasta-el-envo\" data-accordion-index=\"0\" data-title=\"cu-nto-tiempo-pasar-desde-el-pedido-hasta-el-env-o\" role=\"heading\">\n\n                                                            <span class=\"bdt-ep-accordion-icon bdt-flex-align-right\" aria-hidden=\"true\">\n\n                                                                            <span class=\"bdt-ep-accordion-icon-closed\">\n                                            <i aria-hidden=\"true\" class=\"fa-fw fas fa-caret-down\"><\/i>                                        <\/span>\n                                    \n                                                                            <span class=\"bdt-ep-accordion-icon-opened\">\n                                            <i aria-hidden=\"true\" class=\"fa-fw fas fa-minus\"><\/i>                                        <\/span>\n                                    \n                                <\/span>\n                            \n                            <span class=\"bdt-ep-title-text bdt-flex bdt-flex-middle\">\n\n                                                                \u00bfCu\u00e1nto tiempo pasar\u00e1 desde el pedido hasta el env\u00edo?                            <\/span>\n\n                        <\/div>\n                        <div class=\"bdt-ep-accordion-content bdt-accordion-content\">\n                            <p>El tiempo estimado de producci\u00f3n ser\u00e1 de alrededor de 130 d\u00edas, desde la recepci\u00f3n del pedido, pago del dep\u00f3sito y\/o L\/C.<\/p>                        <\/div>\n                    <\/div>\n                                    <div class=\"bdt-ep-accordion-item\">\n                        <div class=\"bdt-ep-accordion-title bdt-accordion-title bdt-flex bdt-flex-middle bdt-flex-between\" id=\"bdt-ep-accordion-envan-ingenieros-a-la-instalacin\" data-accordion-index=\"1\" data-title=\"env-an-ingenieros-a-la-instalaci-n\" role=\"heading\">\n\n                                                            <span class=\"bdt-ep-accordion-icon bdt-flex-align-right\" aria-hidden=\"true\">\n\n                                                                            <span class=\"bdt-ep-accordion-icon-closed\">\n                                            <i aria-hidden=\"true\" class=\"fa-fw fas fa-caret-down\"><\/i>                                        <\/span>\n                                    \n                                                                            <span class=\"bdt-ep-accordion-icon-opened\">\n                                            <i aria-hidden=\"true\" class=\"fa-fw fas fa-minus\"><\/i>                                        <\/span>\n                                    \n                                <\/span>\n                            \n                            <span class=\"bdt-ep-title-text bdt-flex bdt-flex-middle\">\n\n                                                                \u00bfEnv\u00edan ingenieros a la instalaci\u00f3n?                            <\/span>\n\n                        <\/div>\n                        <div class=\"bdt-ep-accordion-content bdt-accordion-content\">\n                            <p>Nuestra empresa contratar\u00e1 a 2 personas como instaladores gu\u00eda y el cliente contratar\u00e1 a los instaladores. Suele tardar entre 60 y 90 d\u00edas, dependiendo de la cantidad de equipos adquiridos.<\/p>                        <\/div>\n                    <\/div>\n                                    <div class=\"bdt-ep-accordion-item\">\n                        <div class=\"bdt-ep-accordion-title bdt-accordion-title bdt-flex bdt-flex-middle bdt-flex-between\" id=\"bdt-ep-accordion-su-mquina-tiene-una-alta-tasa-de-retorno-cunto-tiempo-tardar-en-regresar\" data-accordion-index=\"2\" data-title=\"su-m-quina-tiene-una-alta-tasa-de-retorno-cu-nto-tiempo-tardar-en-regresar\" role=\"heading\">\n\n                                                            <span class=\"bdt-ep-accordion-icon bdt-flex-align-right\" aria-hidden=\"true\">\n\n                                                                            <span class=\"bdt-ep-accordion-icon-closed\">\n                                            <i aria-hidden=\"true\" class=\"fa-fw fas fa-caret-down\"><\/i>                                        <\/span>\n                                    \n                                                                            <span class=\"bdt-ep-accordion-icon-opened\">\n                                            <i aria-hidden=\"true\" class=\"fa-fw fas fa-minus\"><\/i>                                        <\/span>\n                                    \n                                <\/span>\n                            \n                            <span class=\"bdt-ep-title-text bdt-flex bdt-flex-middle\">\n\n                                                                \u00bfSu m\u00e1quina tiene una alta tasa de retorno? \u00bfCu\u00e1nto tiempo tardar\u00e1 en regresar?                            <\/span>\n\n                        <\/div>\n                        <div class=\"bdt-ep-accordion-content bdt-accordion-content\">\n                            <p>La tasa de rendimiento es alta y normalmente se amortiza en 2 o 3 a\u00f1os.<\/p>                        <\/div>\n                    <\/div>\n                                    <div class=\"bdt-ep-accordion-item\">\n                        <div class=\"bdt-ep-accordion-title bdt-accordion-title bdt-flex bdt-flex-middle bdt-flex-between\" id=\"bdt-ep-accordion-cuntos-pases-utilizaron-su-equipo\" data-accordion-index=\"3\" data-title=\"cu-ntos-pa-ses-utilizaron-su-equipo\" role=\"heading\">\n\n                                                            <span class=\"bdt-ep-accordion-icon bdt-flex-align-right\" aria-hidden=\"true\">\n\n                                                                            <span class=\"bdt-ep-accordion-icon-closed\">\n                                            <i aria-hidden=\"true\" class=\"fa-fw fas fa-caret-down\"><\/i>                                        <\/span>\n                                    \n                                                                            <span class=\"bdt-ep-accordion-icon-opened\">\n                                            <i aria-hidden=\"true\" class=\"fa-fw fas fa-minus\"><\/i>                                        <\/span>\n                                    \n                                <\/span>\n                            \n                            <span class=\"bdt-ep-title-text bdt-flex bdt-flex-middle\">\n\n                                                                \u00bfCu\u00e1ntos pa\u00edses utilizaron su equipo?                            <\/span>\n\n                        <\/div>\n                        <div class=\"bdt-ep-accordion-content bdt-accordion-content\">\n                            <p>HGHY ha ayudado a m\u00e1s de 300 clientes en m\u00e1s de 60 pa\u00edses a instalar sus plantas con capacidad l\u00edder y producci\u00f3n de calidad superior.<\/p>                        <\/div>\n                    <\/div>\n                            <\/div>\n        <\/div>\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>HGHY M\u00e1quina De Cubiertos Biodegradables &#8211; cubiertos biodegradables, cubiertos desechables biodegradables y cubiertos desechables ecol\u00f3gicos.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #204b29;\"><strong>Capacidad Diaria: Hasta 500KG<\/strong><\/span><\/p>\n","protected":false},"featured_media":4291,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_joinchat":[]},"product_cat":[229],"product_tag":[],"class_list":{"0":"post-5141","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-linea-productos-cubiertos-biodegradables","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.hghypackaging.com\/es\/wp-json\/wp\/v2\/product\/5141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hghypackaging.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.hghypackaging.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hghypackaging.com\/es\/wp-json\/wp\/v2\/comments?post=5141"}],"version-history":[{"count":0,"href":"https:\/\/www.hghypackaging.com\/es\/wp-json\/wp\/v2\/product\/5141\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hghypackaging.com\/es\/wp-json\/wp\/v2\/media\/4291"}],"wp:attachment":[{"href":"https:\/\/www.hghypackaging.com\/es\/wp-json\/wp\/v2\/media?parent=5141"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.hghypackaging.com\/es\/wp-json\/wp\/v2\/product_cat?post=5141"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.hghypackaging.com\/es\/wp-json\/wp\/v2\/product_tag?post=5141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}